{"id":5750,"date":"2021-10-08T11:47:30","date_gmt":"2021-10-08T10:47:30","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=5750"},"modified":"2021-11-11T16:43:34","modified_gmt":"2021-11-11T16:43:34","slug":"a-cim-bse-ve-aprovada-a-candidatura-de-detecao-e-combate-a-vespa-velutina","status":"publish","type":"post","link":"https:\/\/mixlifeweb.com\/cimrbse\/comunicacao\/a-cim-bse-ve-aprovada-a-candidatura-de-detecao-e-combate-a-vespa-velutina\/","title":{"rendered":"A CIM-BSE v\u00ea aprovada a candidatura de dete\u00e7\u00e3o e combate \u00e0 Vespa velutina"},"content":{"rendered":"<p>A Comunidade Intermunicipal das Beiras e Serra da Estrela (CIM-BSE), no \u00e2mbito do Programa Operacional Sustentabilidade e Efici\u00eancia no Uso de Recursos (POSEUR), viu aprovada a candidatura &#8211; POSEUR-03-2215-FC-000166 \u00a0\u201cImplementa\u00e7\u00e3o de uma estrat\u00e9gia de Preven\u00e7\u00e3o, Controlo e Erradica\u00e7\u00e3o da <em>Vespa velutina<\/em> na Regi\u00e3o das Beiras e Serra da Estrela\u201d, com um investimento eleg\u00edvel de aproximadamente trezentos e quarenta e um mil euros, para monitorizar, prevenir e controlar a dissemina\u00e7\u00e3o e evolu\u00e7\u00e3o da <em>Vespa velutina<\/em> (vespa asi\u00e1tica) no seu territ\u00f3rio.<\/p>\n<p>O projeto tem como objetivo a implementa\u00e7\u00e3o de uma estrat\u00e9gia integrada e coordenada para o territ\u00f3rio da Comunidade Intermunicipal das Beiras e Serra da Estrela, comum aos 15 munic\u00edpios que a integram, estruturada com o \u201cPlano de A\u00e7\u00e3o para a Vigil\u00e2ncia e Controlo da Vespa velutina \u2013 em Portugal\u201d, refor\u00e7ando a capacita\u00e7\u00e3o dos munic\u00edpios com aquisi\u00e7\u00e3o de equipamentos para destrui\u00e7\u00e3o de ninhos, para a vigil\u00e2ncia e monitoriza\u00e7\u00e3o atrav\u00e9s da instala\u00e7\u00e3o de armadilhas e da divulga\u00e7\u00e3o da problem\u00e1tica associada \u00e0 introdu\u00e7\u00e3o desta esp\u00e9cie ex\u00f3tica invasora em Portugal Continental e a promo\u00e7\u00e3o da sensibiliza\u00e7\u00e3o p\u00fablica para os riscos associados \u00a0para ado\u00e7\u00e3o de boas pr\u00e1ticas.<\/p>\n<p>Com a concretiza\u00e7\u00e3o das a\u00e7\u00f5es previstas na candidatura a Comunidade Intermunicipal das Beiras e Serra da Estrela, contribuir\u00e1 significativamente, a m\u00e9dio-longo prazo e de forma sustent\u00e1vel, para uma melhor gest\u00e3o e controlo da <em>Vespa velutina<\/em>, prevenindo e detetando de forma precoce a sua dissemina\u00e7\u00e3o e nos locais onde j\u00e1 se encontra instalada, a sua erradica\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2021\/10\/POSEUR_PT2020_FC_Bom-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6145\" src=\"https:\/\/mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2021\/10\/POSEUR_PT2020_FC_Bom-300x52.jpg\" alt=\"\" width=\"340\" height=\"59\" srcset=\"https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2021\/10\/POSEUR_PT2020_FC_Bom-300x52.jpg 300w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2021\/10\/POSEUR_PT2020_FC_Bom-1030x177.jpg 1030w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2021\/10\/POSEUR_PT2020_FC_Bom-768x132.jpg 768w, https:\/\/www.mixlifeweb.com\/cimrbse\/wp-content\/uploads\/2021\/10\/POSEUR_PT2020_FC_Bom-scaled.jpg 1440w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Para mais informa\u00e7\u00f5es contate o Gabinete T\u00e9cnico Florestal da Comunidade Intermunicipal das Beiras e Serra da Estrela.<\/p>\n<p>Contacto: 271\u00a0205 350<\/p>\n<p>Email: geral@cimbse.pt<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comunidade Intermunicipal das Beiras e Serra da Estrela (CIM-BSE), no \u00e2mbito do Programa Operacional Sustentabilidade e Efici\u00eancia no Uso de Recursos (POSEUR), viu aprovada a candidatura &#8211; POSEUR-03-2215-FC-000166 \u00a0\u201cImplementa\u00e7\u00e3o de uma estrat\u00e9gia de Preven\u00e7\u00e3o, Controlo e Erradica\u00e7\u00e3o da Vespa velutina na Regi\u00e3o das Beiras e Serra da Estrela\u201d, com um investimento eleg\u00edvel de aproximadamente [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":5751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[170],"class_list":["post-5750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias","tag-vespa-velutina"],"acf":[],"_links":{"self":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/5750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=5750"}],"version-history":[{"count":4,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/5750\/revisions"}],"predecessor-version":[{"id":6147,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/5750\/revisions\/6147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/5751"}],"wp:attachment":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=5750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=5750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=5750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}