{"id":4440,"date":"2021-01-25T14:21:46","date_gmt":"2021-01-25T14:21:46","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=4440"},"modified":"2021-01-25T14:21:55","modified_gmt":"2021-01-25T14:21:55","slug":"cim-bse-deu-a-conhecer-o-melhor-do-territorio-na-praca-da-alegria-da-rtp","status":"publish","type":"post","link":"https:\/\/mixlifeweb.com\/cimrbse\/comunicacao\/cim-bse-deu-a-conhecer-o-melhor-do-territorio-na-praca-da-alegria-da-rtp\/","title":{"rendered":"CIM-BSE deu a conhecer o melhor do Territ\u00f3rio na Pra\u00e7a da Alegria da RTP"},"content":{"rendered":"<p>Esta segunda-feira, dia 25 de janeiro, a Comunidade Intermunicipal das Beiras e da Serra da Estrela (CIM-BSE) esteve no programa da manh\u00e3 da Pra\u00e7a da Alegria da RTP, para mostrar e divulgar o melhor do seu territ\u00f3rio e dos seus 15 munic\u00edpios. Dados os constrangimentos provocados pela crise pand\u00e9mica e o atual estado de confinamento geral a que os portugueses est\u00e3o obrigados, a CIM-BSE levou ao programa da esta\u00e7\u00e3o p\u00fablica v\u00e1rias tem\u00e1ticas com o intuito de dar a conhecer \u201ca outra Serra\u201d para al\u00e9m da neve &#8211; a Serra das suas gentes, dos seus produtos end\u00f3genos, das suas mais-valias para a sa\u00fade e bem-estar. Tudo para que quando for poss\u00edvel sairmos deste confinamento, sabermos que h\u00e1 todo um territ\u00f3rio para descobrir e recuperar o tempo perdido.<\/p>\n<p>\u201cSe n\u00e3o pode vir \u00e0 Serra, a Serra vem at\u00e9 si\u201d \u2013 este foi o mote dado no programa apresentado por S\u00f3nia Ara\u00fajo e Jorge Gabriel para que os portugueses ficarem a conhecer a iniciativa inovadora \u201cSomos Serra da Estrela\u201d, promovida pela CIM-BSE, e que tem como prop\u00f3sito primordial: h\u00e1 um outro lado da Serra da Estrela que ainda est\u00e1 por descobrir e que vai muito al\u00e9m dos roteiros tur\u00edsticos.<br \/>\nNa Pra\u00e7a da Alegria divulgamos alguns dos sabores intensos e tradicionais dos 15 munic\u00edpios, tamb\u00e9m disponibilizados online no site Visite Serra da Estrela, e ouvimos pela voz das suas gentes, tem\u00e1ticas identificativas e diferenciadoras do territ\u00f3rio. De M\u00eada ao Fund\u00e3o, passando por Trancoso, Fornos de Algodres, Gouveia, Manteigas, Seia, Covilh\u00e3, Belmonte, Sabugal, Guarda, Celorico da Beira, Pinhel, Almeida e Figueira de Castelo Rodrigo h\u00e1 muito para descobrir e na Pra\u00e7a da Alegria desvendamos um pouco de cada Munic\u00edpio.<\/p>\n<p>\u201cA CIM-BSE acredita que, num mundo cada vez mais homog\u00e9neo e globalizante em todos as suas dimens\u00f5es, e numa altura particularmente complicada para as economias locais dado o atual contexto, \u00e9 preciso passar esta mensagem. Quando retomarmos as nossas vidas, os portugueses n\u00e3o podem esquecer que, \u00e0 semelhan\u00e7a do que aconteceu no ver\u00e3o de 2020, \u00e9 preciso reerguer e isso traduz-se no regresso dos turistas ao nosso Territ\u00f3rio. Traduz-se no consumo do que \u00e9 verdadeiramente genu\u00edno, identit\u00e1rio e nosso\u201d, sustenta o 1\u00ba secret\u00e1rio executivo da CIM-BSE, Ant\u00f3nio Ruas.<\/p>\n<p>A presen\u00e7a da CIM-BSE no programa Pra\u00e7a da Alegria foi sustentada pela divulga\u00e7\u00e3o da marca Serra da Estrela, Um Destino em Estado Puro e pela campanha \u201cSomos Serra da Estrela\u201d, promovida pela CIM-BSE, no \u00e2mbito do projeto \u2018Produtos Tur\u00edsticos Integrados de Base Intermunicipal &#8211; \u00c0 Descoberta da Serra da Estrela\u2019, cofinanciado pelo Centro 2020, Portugal 2020 e Uni\u00e3o Europeia, atrav\u00e9s do Fundo Europeu de Desenvolvimento Regional.<\/p>\n<p>\u201cVisite a Serra da Estrela\u201d<br \/>\nSite I Instagram I Facebook<\/p>\n<p>Contactos CIM-BSE<br \/>\n271 205 350 I geral@cimbse.pt<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta segunda-feira, dia 25 de janeiro, a Comunidade Intermunicipal das Beiras e da Serra da Estrela (CIM-BSE) esteve no programa da manh\u00e3 da Pra\u00e7a da Alegria da RTP, para mostrar e divulgar o melhor do seu territ\u00f3rio e dos seus 15 munic\u00edpios. Dados os constrangimentos provocados pela crise pand\u00e9mica e o atual estado de confinamento [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[],"class_list":["post-4440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=4440"}],"version-history":[{"count":2,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4440\/revisions"}],"predecessor-version":[{"id":4444,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4440\/revisions\/4444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/4441"}],"wp:attachment":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=4440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=4440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=4440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}