{"id":4209,"date":"2020-07-15T15:32:24","date_gmt":"2020-07-15T14:32:24","guid":{"rendered":"https:\/\/www.mixlifeweb.com\/cimrbse\/?p=4209"},"modified":"2020-07-17T14:20:05","modified_gmt":"2020-07-17T13:20:05","slug":"a-comunidade-intermunicipal-das-beiras-e-serra-da-estrela-promove-a-marca-serra-da-estrela-um-destino-em-estado-puro","status":"publish","type":"post","link":"https:\/\/mixlifeweb.com\/cimrbse\/comunicacao\/a-comunidade-intermunicipal-das-beiras-e-serra-da-estrela-promove-a-marca-serra-da-estrela-um-destino-em-estado-puro\/","title":{"rendered":"A Comunidade Intermunicipal das Beiras e Serra da Estrela promove a marca \u201cSerra da Estrela: Um destino em Estado Puro\u201d"},"content":{"rendered":"<p>A CIMBSE procedeu \u00e0 coloca\u00e7\u00e3o de outdoors nas autoestradas, com o objetivo de promover a marca \u201cSerra da Estrela: Um destino Destino em Estado Puro\u201d.<\/p>\n<p>Esta a\u00e7\u00e3o foi realizada no \u00e2mbito da Candidatura n\u00ba CENTRO-07-2114-FEDER-000064 \u2013 \u00c0 Descoberta da Serra da Estrela.<\/p>\n<p>O presente ano trouxe in\u00famero desafios. Os h\u00e1bitos de turismo nesta \u00e9poca de pandemia est\u00e3o a alterar-se profundamente, sendo cada vez mais as pessoas que escolhem o Interior como o seu destino de f\u00e9rias. Esta \u00e9 a oportunidade para consolidar a marca e o territ\u00f3rio enquanto destino Tur\u00edstico de Excel\u00eancia, com in\u00fameras ofertas, perfeito para toda a fam\u00edlia.<\/p>\n<p>Visite-nos em <a href=\"http:\/\/www.serradaestrela.pt\">www.visiteserradaestrela.pt<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A CIMBSE procedeu \u00e0 coloca\u00e7\u00e3o de outdoors nas autoestradas, com o objetivo de promover a marca \u201cSerra da Estrela: Um destino Destino em Estado Puro\u201d. Esta a\u00e7\u00e3o foi realizada no \u00e2mbito da Candidatura n\u00ba CENTRO-07-2114-FEDER-000064 \u2013 \u00c0 Descoberta da Serra da Estrela. O presente ano trouxe in\u00famero desafios. Os h\u00e1bitos de turismo nesta \u00e9poca de [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":4226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[],"class_list":["post-4209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=4209"}],"version-history":[{"count":4,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4209\/revisions"}],"predecessor-version":[{"id":4225,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/4209\/revisions\/4225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/4226"}],"wp:attachment":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=4209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=4209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=4209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}