{"id":1655,"date":"2017-05-24T10:28:40","date_gmt":"2017-05-24T10:28:40","guid":{"rendered":"http:\/\/cimbse.pt\/?p=1655"},"modified":"2017-05-24T10:28:40","modified_gmt":"2017-05-24T10:28:40","slug":"sessao-apresentacao-indice-transparencia-municipal","status":"publish","type":"post","link":"https:\/\/mixlifeweb.com\/cimrbse\/comunicacao\/sessao-apresentacao-indice-transparencia-municipal\/","title":{"rendered":"SESS\u00c3O DE APRESENTA\u00c7\u00c3O \u00cdNDICE DE TRANSPAR\u00caNCIA MUNICIPAL"},"content":{"rendered":"<p>A Comunidade Intermunicipal Beiras e Serra da Estrela(CIMBSE), ir\u00e1 promover a sess\u00e3o de apresenta\u00e7\u00e3o dos resultados do \u00edndice de transpar\u00eancia municipal\/CIMBSE e dissemina\u00e7\u00e3o de boas pr\u00e1ticas no uso das TIC\u00b4s, em parceria com a Transpar\u00eancia e Integridade \u2013 Associa\u00e7\u00e3o C\u00edvica, no dia 1 de junho do corrente ano pelas 15 horas na sala Ant\u00f3nio Almeida Santos Munic\u00edpio da Guarda.<\/p>\n<p>\u201cO \u00cdndice de Transpar\u00eancia Municipal (ITM) mede o grau de transpar\u00eancia das C\u00e2maras Municipais atrav\u00e9s de uma an\u00e1lise da informa\u00e7\u00e3o disponibilizada aos cidad\u00e3os nos seus web sites. O ITM \u00e9 composto por 76 indicadores agrupados em sete dimens\u00f5es: 1) Informa\u00e7\u00e3o sobre a Organiza\u00e7\u00e3o, Composi\u00e7\u00e3o Social e Funcionamento do Munic\u00edpio; 2) Planos e Relat\u00f3rios; 3) Impostos, Taxas, Tarifas, Pre\u00e7os e Regulamentos; 4) Rela\u00e7\u00e3o com a Sociedade; 5) Contrata\u00e7\u00e3o P\u00fablica; 6) Transpar\u00eancia Econ\u00f3mico-Financeira; 7) Transpar\u00eancia na \u00e1rea do Urbanismo.<\/p>\n<p>O Poder Local constitui uma pedra angular da democracia Portuguesa, pelo papel fundamental que desempenha para o desenvolvimento das comunidades locais e a forma\u00e7\u00e3o c\u00edvica dos cidad\u00e3os.<\/p>\n<p>\u00c9 un\u00e2nime o reconhecimento do servi\u00e7o prestado pelo Poder Local \u00e0 consolida\u00e7\u00e3o democr\u00e1tica e ao desenvolvimento do pa\u00eds.\u201d<\/p>\n<p>Fonte: https:\/\/transparencia.pt\/projetos\/indice-de-transparencia-municipal\/<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comunidade Intermunicipal Beiras e Serra da Estrela(CIMBSE), ir\u00e1 promover a sess\u00e3o de apresenta\u00e7\u00e3o dos resultados do \u00edndice de transpar\u00eancia municipal\/CIMBSE e dissemina\u00e7\u00e3o de boas pr\u00e1ticas no uso das TIC\u00b4s, em parceria com a Transpar\u00eancia e Integridade \u2013 Associa\u00e7\u00e3o C\u00edvica, no dia 1 de junho do corrente ano pelas 15 horas na sala Ant\u00f3nio Almeida [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":1657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-1655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao","category-eventos"],"acf":[],"_links":{"self":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/1655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/comments?post=1655"}],"version-history":[{"count":2,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/1655\/revisions"}],"predecessor-version":[{"id":1663,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/posts\/1655\/revisions\/1663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media\/1657"}],"wp:attachment":[{"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/media?parent=1655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/categories?post=1655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mixlifeweb.com\/cimrbse\/wp-json\/wp\/v2\/tags?post=1655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}